{"id":12800,"date":"2025-07-14T08:30:35","date_gmt":"2025-07-14T08:30:35","guid":{"rendered":"https:\/\/blog.netbet.ro\/blog\/?p=12800"},"modified":"2025-07-14T08:30:35","modified_gmt":"2025-07-14T08:30:35","slug":"role-dragalase","status":"publish","type":"post","link":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/","title":{"rendered":"Role dr\u0103g\u0103la\u0219e"},"content":{"rendered":"<p>Tema unui <a href=\"https:\/\/casino.netbet.ro\/\"><strong>slot online<\/strong><\/a> este foarte important\u0103 pentru mul\u021bi dintre juc\u0103torii de casino. Se spune c\u0103 prima impresie conteaz\u0103, iar la p\u0103c\u0103nele aceasta este dat\u0103 de tem\u0103 \u0219i grafic\u0103. Bine\u00een\u021beles, detaliile tehnice \u0219i func\u021biile speciale sunt cele care fac diferen\u021ba, dar \u0219i atmosfera creat\u0103 de joc are rolul ei.<\/p>\n<p>Pentru c\u0103 sunt iubite de foarte mul\u021bi oameni, animalele domestice pot genera o atmosfer\u0103 destins\u0103, cu at\u00e2t mai mult cu c\u00e2t sunt prezentate \u00een ipostaze inedite. Din oferta <a href=\"https:\/\/casino.netbet.ro\/\">NetBet Casino<\/a> am ales pentru tine dou\u0103 sloturi online \u00een care farmecul animalelor de companie este irezistibil.<\/p>\n<h2>Hot Dog Heist de la Play\u2019n GO<\/h2>\n<p><a href=\"https:\/\/casino.netbet.ro\/play\/hot-dog-heist\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-12803\" src=\"https:\/\/blog.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1200x628_Hot-Dog-Heist-1024x536.jpg\" alt=\"\" width=\"1024\" height=\"536\" srcset=\"https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1200x628_Hot-Dog-Heist-1024x536.jpg 1024w, https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1200x628_Hot-Dog-Heist-300x157.jpg 300w, https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1200x628_Hot-Dog-Heist-768x402.jpg 768w, https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1200x628_Hot-Dog-Heist.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Hot Dog Heist este un slot online dezvoltat de compania suedez\u0103 Play\u2019n GO. Disponibil din decembrie 2024, el ne prezint\u0103 aventurile a 5 c\u0103\u021belu\u0219i, mari amatori de hot dog. Prinde-i \u00een fapt pe ace\u0219ti 5 ho\u021bomani \u0219i po\u021bi revendica recompense de p\u00e2n\u0103 la 2.500x miza dup\u0103 un model matematic cu RTP de 94.57%.<\/p>\n<p>Jocul este construit pe o schem\u0103 5&#215;4 care activeaz\u0103 40 de linii de plat\u0103 fixe. Rough Collie, Border Collie, Labradorul \u0219i Buldogul sunt simbolurile cu valoare ridicat\u0103. Simbolurile cu valoare redus\u0103 sunt reprezentate de suita de la 9 la A din pachetul de c\u0103r\u021bi de joc. Golden Retriever-ul este Wild \u0219i supline\u0219te celelalte simboluri \u00een combina\u021bii.<\/p>\n<p>Recompensele sunt mai generoase \u00een timpul rundei bonus Hot Dog Heist Free Spins ini\u021biat\u0103 de 3 simboluri Scatter (Gr\u0103tar). Roata Bonus va selecta una dintre cele 7 variante ale acestuia:<\/p>\n<ul>\n<li>Pachetul &#8211; 3 rotiri gratuite \u0219i simboluri 4&#215;4 pe rolele 2-5<\/li>\n<li>Golden Retriever &#8211; 3 rotiri gratuite cu 1 sau 2 role Wild<\/li>\n<li>Rough Collie &#8211; 1 rotire gratuit\u0103 cu simbol Rough Collie 3&#215;3 sau 3&#215;4 pe rolele 2-4. C\u00e2nd blocul este expus total, se acord\u0103 un re-spin cu simbolul Mega blocat.<\/li>\n<li>Labrador &#8211; 1 rotire gratuit\u0103 cu multiplicator de c\u00e2\u0219tiguri cuprins \u00eentre 5X \u0219i 30X.<\/li>\n<li>Border Collie &#8211; 1 rotire gratuit\u0103 cu simbol Border Collie Wild 2&#215;2 \u0219i re-rotire cu simbolurile Border Collie Wild blocate<\/li>\n<li>Bulldog &#8211; 1 rotire gratuit\u0103 cu 2 simboluri Bulldog 2&#215;2 \u0219i re-rotire cu aceste simboluri blocate.<\/li>\n<li>Cine este un c\u00e2ine bun? &#8211; bonus de tip pick-em.<\/li>\n<\/ul>\n<p>Secven\u021ba bonus \u201eCine este un c\u00e2ine bun?\u201d se joac\u0103 pe un panou 5&#215;4. Select\u00e2nd pozi\u021bii vei dezv\u0103lui premii instant cuprinse \u00eentre 0.25x \u0219i 25x, dar \u0219i secven\u021be bonus. C\u00e2nd selectezi secven\u021bele Pachetul sau Golden Retriever, dup\u0103 rularea acestora func\u021bia se termin\u0103. Dac\u0103 selectezi celelalte bonusuri, dup\u0103 finalizare, func\u021bia \u201eCine este un c\u00e2ine bun?\u201d se reia p\u00e2n\u0103 vei dezv\u0103lui un \u201eX\u201d (dou\u0103 oase \u00eencruci\u0219ate).<\/p>\n<h2>Fonzo\u2019s Feline Fortune de la Pragmatic Play<\/h2>\n<p><a href=\"https:\/\/casino.netbet.ro\/play\/fonzos-feline-fortunes\"><img decoding=\"async\" class=\"alignnone size-large wp-image-12802\" src=\"https:\/\/blog.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1200x628_Fonzos-Feline-Fortune-1024x536.jpg\" alt=\"\" width=\"1024\" height=\"536\" srcset=\"https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1200x628_Fonzos-Feline-Fortune-1024x536.jpg 1024w, https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1200x628_Fonzos-Feline-Fortune-300x157.jpg 300w, https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1200x628_Fonzos-Feline-Fortune-768x402.jpg 768w, https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1200x628_Fonzos-Feline-Fortune.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>\u00cen slotul online Fonzo\u2019s Feline Fortune lansat de Pragmatic Play \u00een decembrie 2024, vedeta este Fonzo, o pisic\u0103 pasionat\u0103 de chiroman\u021bie, dar foarte atras\u0103 de \u201epl\u0103cerile lume\u0219ti\u201d. Fonzo este simbolul Wild \u0219i supline\u0219te \u00een combina\u021bii simbolurile curente: Sticla de lapte, Scheletul de pe\u0219te, Ghemul de a\u021b\u0103, \u0218oricelul mecanic \u0219i suita de la 10 al A din pachetul de c\u0103r\u021bi de joc.<\/p>\n<p>Modelul matematic, foarte volatil, cu RTP de 96.50% te poate recompensa cu p\u00e2n\u0103 la 5.000x miza. Pentru a ob\u021bine premii mari trebuie s\u0103 activezi func\u021biile speciale ale jocului. \u00cen mod aleatoriu, la finalul oric\u0103rei rotiri se poate declan\u0219a un re-spin gratuit sau o serie de re-spinuri cu role speciale care pot activa 2 role Wild, 3 role Wild, cel pu\u021bin 3 dintre simbolurile cu valoare ridicat\u0103 sau cel pu\u021bin 2 simboluri Scatter. \u00cen ultimul caz, poate fi ad\u0103ugat oriunde pe role un simbol Scatter pentru a declan\u0219a rotirile gratuite.<\/p>\n<p>3, 4 sau 5 Scattere (L\u0103bu\u021be) ini\u021biaz\u0103 bonusul cu 10, 20 sau 30 de rotiri gratuite cu multiplicator progresiv la redeclan\u0219are. Activ\u00e2nd Modul Miz\u0103, pentru 50% \u00een plus la miz\u0103, vei dubla \u0219ansele s\u0103 declan\u0219ezi bonusul.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tema unui slot online este foarte important\u0103 pentru mul\u021bi dintre juc\u0103torii de casino. Se spune c\u0103 prima impresie conteaz\u0103, iar<\/p>\n","protected":false},"author":25,"featured_media":12806,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[447],"tags":[],"class_list":["post-12800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cazino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Role dr\u0103g\u0103la\u0219e | NetBet Blog Romania<\/title>\n<meta name=\"description\" content=\"Tema unui slot online este foarte important\u0103 pentru mul\u021bi dintre juc\u0103torii de casino. Din oferta NetBet Casino am ales pentru tine sloturi online \u00een care farmecul animalelor de companie este irezistibil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Role dr\u0103g\u0103la\u0219e | NetBet Blog Romania\" \/>\n<meta property=\"og:description\" content=\"Tema unui slot online este foarte important\u0103 pentru mul\u021bi dintre juc\u0103torii de casino. Din oferta NetBet Casino am ales pentru tine sloturi online \u00een care farmecul animalelor de companie este irezistibil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/\" \/>\n<meta property=\"og:site_name\" content=\"NetBet Blog Romania\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/netbetcom\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-14T08:30:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1200x628_6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ruxandra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@netbet\" \/>\n<meta name=\"twitter:site\" content=\"@netbet\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ruxandra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/2025\\\/07\\\/14\\\/role-dragalase\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/2025\\\/07\\\/14\\\/role-dragalase\\\/\"},\"author\":{\"name\":\"Ruxandra\",\"@id\":\"https:\\\/\\\/blog.netbet.ro\\\/blog\\\/#\\\/schema\\\/person\\\/93552020db93a7b5bcaca92067e5b3e8\"},\"headline\":\"Role dr\u0103g\u0103la\u0219e\",\"datePublished\":\"2025-07-14T08:30:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/2025\\\/07\\\/14\\\/role-dragalase\\\/\"},\"wordCount\":649,\"image\":{\"@id\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/2025\\\/07\\\/14\\\/role-dragalase\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/NB_1080x1080_6.jpg\",\"articleSection\":[\"Cazino\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/2025\\\/07\\\/14\\\/role-dragalase\\\/\",\"url\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/2025\\\/07\\\/14\\\/role-dragalase\\\/\",\"name\":\"Role dr\u0103g\u0103la\u0219e | NetBet Blog Romania\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.netbet.ro\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/2025\\\/07\\\/14\\\/role-dragalase\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/2025\\\/07\\\/14\\\/role-dragalase\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/NB_1080x1080_6.jpg\",\"datePublished\":\"2025-07-14T08:30:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.netbet.ro\\\/blog\\\/#\\\/schema\\\/person\\\/93552020db93a7b5bcaca92067e5b3e8\"},\"description\":\"Tema unui slot online este foarte important\u0103 pentru mul\u021bi dintre juc\u0103torii de casino. Din oferta NetBet Casino am ales pentru tine sloturi online \u00een care farmecul animalelor de companie este irezistibil.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/2025\\\/07\\\/14\\\/role-dragalase\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/2025\\\/07\\\/14\\\/role-dragalase\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/2025\\\/07\\\/14\\\/role-dragalase\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/NB_1080x1080_6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/NB_1080x1080_6.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.netbet.ro\\\/blog\\\/2025\\\/07\\\/14\\\/role-dragalase\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.netbet.ro\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Role dr\u0103g\u0103la\u0219e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.netbet.ro\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/blog.netbet.ro\\\/blog\\\/\",\"name\":\"NetBet Blog Romania\",\"description\":\"Facem pariurile mai interesante\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.netbet.ro\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.netbet.ro\\\/blog\\\/#\\\/schema\\\/person\\\/93552020db93a7b5bcaca92067e5b3e8\",\"name\":\"Ruxandra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83b9a25c3816d3a8a8ab71b333e40ef54bad9a23dcb59245a8f08b051275b46a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83b9a25c3816d3a8a8ab71b333e40ef54bad9a23dcb59245a8f08b051275b46a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83b9a25c3816d3a8a8ab71b333e40ef54bad9a23dcb59245a8f08b051275b46a?s=96&d=mm&r=g\",\"caption\":\"Ruxandra\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Role dr\u0103g\u0103la\u0219e | NetBet Blog Romania","description":"Tema unui slot online este foarte important\u0103 pentru mul\u021bi dintre juc\u0103torii de casino. Din oferta NetBet Casino am ales pentru tine sloturi online \u00een care farmecul animalelor de companie este irezistibil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/","og_locale":"en_US","og_type":"article","og_title":"Role dr\u0103g\u0103la\u0219e | NetBet Blog Romania","og_description":"Tema unui slot online este foarte important\u0103 pentru mul\u021bi dintre juc\u0103torii de casino. Din oferta NetBet Casino am ales pentru tine sloturi online \u00een care farmecul animalelor de companie este irezistibil.","og_url":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/","og_site_name":"NetBet Blog Romania","article_publisher":"https:\/\/www.facebook.com\/netbetcom","article_published_time":"2025-07-14T08:30:35+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1200x628_6.jpg","type":"image\/jpeg"}],"author":"Ruxandra","twitter_card":"summary_large_image","twitter_creator":"@netbet","twitter_site":"@netbet","twitter_misc":{"Written by":"Ruxandra","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/#article","isPartOf":{"@id":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/"},"author":{"name":"Ruxandra","@id":"https:\/\/blog.netbet.ro\/blog\/#\/schema\/person\/93552020db93a7b5bcaca92067e5b3e8"},"headline":"Role dr\u0103g\u0103la\u0219e","datePublished":"2025-07-14T08:30:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/"},"wordCount":649,"image":{"@id":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1080x1080_6.jpg","articleSection":["Cazino"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/","url":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/","name":"Role dr\u0103g\u0103la\u0219e | NetBet Blog Romania","isPartOf":{"@id":"https:\/\/blog.netbet.ro\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/#primaryimage"},"image":{"@id":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1080x1080_6.jpg","datePublished":"2025-07-14T08:30:35+00:00","author":{"@id":"https:\/\/blog.netbet.ro\/blog\/#\/schema\/person\/93552020db93a7b5bcaca92067e5b3e8"},"description":"Tema unui slot online este foarte important\u0103 pentru mul\u021bi dintre juc\u0103torii de casino. Din oferta NetBet Casino am ales pentru tine sloturi online \u00een care farmecul animalelor de companie este irezistibil.","breadcrumb":{"@id":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/#primaryimage","url":"https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1080x1080_6.jpg","contentUrl":"https:\/\/www.netbet.ro\/blog\/wp-content\/uploads\/2025\/04\/NB_1080x1080_6.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.netbet.ro\/blog\/2025\/07\/14\/role-dragalase\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.netbet.ro\/blog\/"},{"@type":"ListItem","position":2,"name":"Role dr\u0103g\u0103la\u0219e"}]},{"@type":"WebSite","@id":"https:\/\/blog.netbet.ro\/blog\/#website","url":"https:\/\/blog.netbet.ro\/blog\/","name":"NetBet Blog Romania","description":"Facem pariurile mai interesante","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.netbet.ro\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/blog.netbet.ro\/blog\/#\/schema\/person\/93552020db93a7b5bcaca92067e5b3e8","name":"Ruxandra","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/83b9a25c3816d3a8a8ab71b333e40ef54bad9a23dcb59245a8f08b051275b46a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/83b9a25c3816d3a8a8ab71b333e40ef54bad9a23dcb59245a8f08b051275b46a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83b9a25c3816d3a8a8ab71b333e40ef54bad9a23dcb59245a8f08b051275b46a?s=96&d=mm&r=g","caption":"Ruxandra"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.netbet.ro\/blog\/wp-json\/wp\/v2\/posts\/12800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netbet.ro\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.netbet.ro\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.netbet.ro\/blog\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.netbet.ro\/blog\/wp-json\/wp\/v2\/comments?post=12800"}],"version-history":[{"count":2,"href":"https:\/\/www.netbet.ro\/blog\/wp-json\/wp\/v2\/posts\/12800\/revisions"}],"predecessor-version":[{"id":12825,"href":"https:\/\/www.netbet.ro\/blog\/wp-json\/wp\/v2\/posts\/12800\/revisions\/12825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.netbet.ro\/blog\/wp-json\/wp\/v2\/media\/12806"}],"wp:attachment":[{"href":"https:\/\/www.netbet.ro\/blog\/wp-json\/wp\/v2\/media?parent=12800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.netbet.ro\/blog\/wp-json\/wp\/v2\/categories?post=12800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.netbet.ro\/blog\/wp-json\/wp\/v2\/tags?post=12800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}